{"id":67,"count":10,"description":"","link":"https:\/\/www.nordicjobsabroad.com\/nb\/tag\/jobs","name":"Jobb","slug":"jobber","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jobs Archives - NordicJobsAbroad<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"nb_NO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jobs Archives - NordicJobsAbroad\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nordicjobsabroad.com\/nb\/merke\/jobber\/\" \/>\n<meta property=\"og:site_name\" content=\"NordicJobsAbroad\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/tag\\\/jobs\",\"url\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/tag\\\/jobs\",\"name\":\"Jobs Archives - NordicJobsAbroad\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/tag\\\/jobs#breadcrumb\"},\"inLanguage\":\"nb-NO\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/tag\\\/jobs#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jobs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/en\\\/\",\"name\":\"NordicJobsAbroad\",\"description\":\"Jobs abroad for nordic speakers\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nb-NO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/en\\\/#organization\",\"name\":\"NordicJobsAbroad\",\"url\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nb-NO\",\"@id\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/wp-content\\\/uploads\\\/nordicjobsabroad-logo-new.png\",\"contentUrl\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/wp-content\\\/uploads\\\/nordicjobsabroad-logo-new.png\",\"width\":1536,\"height\":200,\"caption\":\"NordicJobsAbroad\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jobs Archives - NordicJobsAbroad","robots":{"index":"noindex","follow":"follow"},"og_locale":"nb_NO","og_type":"article","og_title":"Jobs Archives - NordicJobsAbroad","og_url":"https:\/\/www.nordicjobsabroad.com\/nb\/merke\/jobber\/","og_site_name":"NordicJobsAbroad","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.nordicjobsabroad.com\/tag\/jobs","url":"https:\/\/www.nordicjobsabroad.com\/tag\/jobs","name":"Jobbarkiv - NordicJobsAbroad","isPartOf":{"@id":"https:\/\/www.nordicjobsabroad.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.nordicjobsabroad.com\/tag\/jobs#breadcrumb"},"inLanguage":"nb-NO"},{"@type":"BreadcrumbList","@id":"https:\/\/www.nordicjobsabroad.com\/tag\/jobs#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.nordicjobsabroad.com\/"},{"@type":"ListItem","position":2,"name":"Jobs"}]},{"@type":"WebSite","@id":"https:\/\/www.nordicjobsabroad.com\/en\/#website","url":"https:\/\/www.nordicjobsabroad.com\/en\/","name":"NordicJobsAbroad","description":"Jobb i utlandet for nordisktalende","publisher":{"@id":"https:\/\/www.nordicjobsabroad.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nordicjobsabroad.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nb-NO"},{"@type":"Organization","@id":"https:\/\/www.nordicjobsabroad.com\/en\/#organization","name":"NordicJobsAbroad","url":"https:\/\/www.nordicjobsabroad.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"nb-NO","@id":"https:\/\/www.nordicjobsabroad.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.nordicjobsabroad.com\/wp-content\/uploads\/nordicjobsabroad-logo-new.png","contentUrl":"https:\/\/www.nordicjobsabroad.com\/wp-content\/uploads\/nordicjobsabroad-logo-new.png","width":1536,"height":200,"caption":"NordicJobsAbroad"},"image":{"@id":"https:\/\/www.nordicjobsabroad.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.nordicjobsabroad.com\/nb\/wp-json\/wp\/v2\/tags\/67","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nordicjobsabroad.com\/nb\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.nordicjobsabroad.com\/nb\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.nordicjobsabroad.com\/nb\/wp-json\/wp\/v2\/posts?tags=67"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}