{"id":381,"date":"2015-07-17T20:20:51","date_gmt":"2015-07-17T20:20:51","guid":{"rendered":"http:\/\/www.nordicjobsabroad.com\/?p=381"},"modified":"2024-02-29T15:03:08","modified_gmt":"2024-02-29T15:03:08","slug":"visum-til-irsk-pass","status":"publish","type":"post","link":"https:\/\/www.nordicjobsabroad.com\/nb\/visum-pas-irland","title":{"rendered":"Visum og pass til Irland"},"content":{"rendered":"<p>F\u00f8lgende visum- og passregler gjelder for norske statsborgere som reiser til Irland:<\/p>\n<ul>\n<li><strong>Visum<\/strong>Visum er ikke p\u00e5krevd de f\u00f8rste 90 dagene.<\/li>\n<\/ul>\n<ul>\n<li><strong>Pass<\/strong>Passet ditt m\u00e5 v\u00e6re gyldig under hele oppholdet i Irland. Utvidede og provisoriske norske pass og EU-n\u00f8dpass anerkjennes.<\/li>\n<\/ul>\n<p>Du trenger ikke \u00e5 vise passet ditt ved grensen ettersom Irland er medlem av EU, men du b\u00f8r ta med deg passet ditt - som ved alle andre internasjonale reiser.<\/p>\n<hr \/>\n<p>Hvis du ikke har norsk pass, kan du kontakte den irske ambassaden i Norge:<\/p>\n\n\n<\/p>\n<p><strong>Irlands ambassade i Norge<\/strong><br \/>\n<strong>6. etasje,<\/strong><br \/>\n<strong>Haakon VIIs gate 1<\/strong><br \/>\n<strong>Postboks 4006 AMB<\/strong><br \/>\n<strong>0244 Oslo, Norge<\/strong><br \/>\n<strong>Telefon: +47 2201 7200<\/strong><br \/>\n<a href=\"https:\/\/www.ireland.ie\/en\/norway\/oslo\/\" class=\"ext-link\" rel=\"nofollow\" target=\"_blank\"><strong>https:\/\/www.ireland.ie\/en\/norway\/oslo\/<\/strong><\/a><\/p>\n<p>\n<hr \/>\n<p>&nbsp;<\/p>\n<h2>Lengre opphold<\/h2>\n<p>Hvis du \u00f8nsker \u00e5 oppholde deg i Irland i mer enn de f\u00f8rste 90 visumfrie dagene, b\u00f8r du som regel kunne fors\u00f8rge deg selv ved hjelp av egne midler eller arbeid. Dette er imidlertid ogs\u00e5 mulig som student. Les mer om dette i artikkelen v\u00e5r om <a href=\"https:\/\/www.nordicjobsabroad.com\/nb\/flytte-til-irland\/\" class=\"local-link\">\u00e5 flytte til Irland<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<h2>Nyttige lenker<\/h2>\n<ul>\n<li><a href=\"https:\/\/www.irishstatutebook.ie\/eli\/2014\/si\/473\/made\/en\/print\" class=\"ext-link\" rel=\"nofollow\" target=\"_blank\">Irsk lovgivning om visumregler<\/a><\/li>\n<li><a href=\"https:\/\/www.dfa.ie\/travel\/visas\/visas-for-ireland\/\" class=\"ext-link\" rel=\"nofollow\" target=\"_blank\">S\u00f8ke om visum i Irland<\/a><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>Du kan ogs\u00e5 lese artiklene v\u00e5re om \u00e5 <a href=\"https:\/\/www.nordicjobsabroad.com\/nb\/jobber-i-irland\/\" class=\"local-link\">finne en jobb i Irland<\/a> og om <a href=\"https:\/\/www.nordicjobsabroad.com\/nb\/arbeid-i-irland\/\" class=\"local-link\">hvordan det er \u00e5 arbeide i Irland<\/a>.<\/p>\n<hr \/>","protected":false},"excerpt":{"rendered":"<p>F\u00f8lgende visum- og passregler gjelder for danske statsborgere som reiser til Irland: Visum: Du trenger ikke visum de f\u00f8rste 90 dagene. Pass: Passet ditt m\u00e5 v\u00e6re gyldig under hele oppholdet i Irland. Utvidede og provisoriske danske pass og EU-n\u00f8dpass anerkjennes. Pass er ikke p\u00e5krevd ved grensen, ettersom Irland er medlem av EUs... <a title=\"Visum og pass til Irland\" class=\"read-more\" href=\"https:\/\/www.nordicjobsabroad.com\/nb\/visum-pas-irland\" aria-label=\"Les mer om visum og pass til Irland\">Les mer<\/a><\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20,45],"tags":[47,68],"class_list":["post-381","post","type-post","status-publish","format-standard","hentry","category-europa","category-irland","tag-irland","tag-visum-pas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Visum og pas til Irland - S\u00e5dan er reglerne for danskere<\/title>\n<meta name=\"description\" content=\"Danskere beh\u00f8ver intet visum til Irland de f\u00f8rste 90 dage af deres ophold. L\u00e6s mere om reglerne for pas og visum til Irland p\u00e5 denne side.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nordicjobsabroad.com\/nb\/visum-til-irsk-pass\/\" \/>\n<meta property=\"og:locale\" content=\"nb_NO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Visum og pas til Irland - S\u00e5dan er reglerne for danskere\" \/>\n<meta property=\"og:description\" content=\"Danskere beh\u00f8ver intet visum til Irland de f\u00f8rste 90 dage af deres ophold. L\u00e6s mere om reglerne for pas og visum til Irland p\u00e5 denne side.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nordicjobsabroad.com\/nb\/visum-til-irsk-pass\/\" \/>\n<meta property=\"og:site_name\" content=\"NordicJobsAbroad\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-17T20:20:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-29T15:03:08+00:00\" \/>\n<meta name=\"author\" content=\"Jesper\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Skrevet av\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jesper\" \/>\n\t<meta name=\"twitter:label2\" content=\"Ansl. lesetid\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutter\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/visum-pas-irland#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/visum-pas-irland\"},\"author\":{\"name\":\"Jesper\",\"@id\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/en\\\/#\\\/schema\\\/person\\\/13dfb8e4bfd8eda10d75a65b2405d3a0\"},\"headline\":\"Visum og pas til Irland\",\"datePublished\":\"2015-07-17T20:20:51+00:00\",\"dateModified\":\"2024-02-29T15:03:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/visum-pas-irland\"},\"wordCount\":269,\"publisher\":{\"@id\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/en\\\/#organization\"},\"keywords\":[\"Irland\",\"Visum - pas\"],\"articleSection\":[\"Europa\",\"Irland\"],\"inLanguage\":\"nb-NO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/visum-pas-irland\",\"url\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/visum-pas-irland\",\"name\":\"Visum og pas til Irland - S\u00e5dan er reglerne for danskere\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/en\\\/#website\"},\"datePublished\":\"2015-07-17T20:20:51+00:00\",\"dateModified\":\"2024-02-29T15:03:08+00:00\",\"description\":\"Danskere beh\u00f8ver intet visum til Irland de f\u00f8rste 90 dage af deres ophold. L\u00e6s mere om reglerne for pas og visum til Irland p\u00e5 denne side.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/visum-pas-irland#breadcrumb\"},\"inLanguage\":\"nb-NO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.nordicjobsabroad.com\\\/visum-pas-irland\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/visum-pas-irland#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Visum og pas til Irland\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/en\\\/\",\"name\":\"NordicJobsAbroad\",\"description\":\"Jobs abroad for nordic speakers\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nb-NO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/en\\\/#organization\",\"name\":\"NordicJobsAbroad\",\"url\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nb-NO\",\"@id\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/wp-content\\\/uploads\\\/nordicjobsabroad-logo-new.png\",\"contentUrl\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/wp-content\\\/uploads\\\/nordicjobsabroad-logo-new.png\",\"width\":1536,\"height\":200,\"caption\":\"NordicJobsAbroad\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/en\\\/#\\\/schema\\\/person\\\/13dfb8e4bfd8eda10d75a65b2405d3a0\",\"name\":\"Jesper\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nb-NO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ff46f83ce962a741bd719be7cb170e6ec9041c021a913406ca1498bec6a5b7e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ff46f83ce962a741bd719be7cb170e6ec9041c021a913406ca1498bec6a5b7e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ff46f83ce962a741bd719be7cb170e6ec9041c021a913406ca1498bec6a5b7e?s=96&d=mm&r=g\",\"caption\":\"Jesper\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Visum og pass til Irland - Hvilke regler gjelder for nordmenn?","description":"Nordmenn trenger ikke visum til Irland de f\u00f8rste 90 dagene av oppholdet. Les mer om pass- og visumregler for Irland p\u00e5 denne siden.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nordicjobsabroad.com\/nb\/visum-til-irsk-pass\/","og_locale":"nb_NO","og_type":"article","og_title":"Visum og pas til Irland - S\u00e5dan er reglerne for danskere","og_description":"Danskere beh\u00f8ver intet visum til Irland de f\u00f8rste 90 dage af deres ophold. L\u00e6s mere om reglerne for pas og visum til Irland p\u00e5 denne side.","og_url":"https:\/\/www.nordicjobsabroad.com\/nb\/visum-til-irsk-pass\/","og_site_name":"NordicJobsAbroad","article_published_time":"2015-07-17T20:20:51+00:00","article_modified_time":"2024-02-29T15:03:08+00:00","author":"Jesper","twitter_card":"summary_large_image","twitter_misc":{"Skrevet av":"Jesper","Ansl. lesetid":"2 minutter"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.nordicjobsabroad.com\/visum-pas-irland#article","isPartOf":{"@id":"https:\/\/www.nordicjobsabroad.com\/visum-pas-irland"},"author":{"name":"Jesper","@id":"https:\/\/www.nordicjobsabroad.com\/en\/#\/schema\/person\/13dfb8e4bfd8eda10d75a65b2405d3a0"},"headline":"Visum og pas til Irland","datePublished":"2015-07-17T20:20:51+00:00","dateModified":"2024-02-29T15:03:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.nordicjobsabroad.com\/visum-pas-irland"},"wordCount":269,"publisher":{"@id":"https:\/\/www.nordicjobsabroad.com\/en\/#organization"},"keywords":["Irland","Visum - pas"],"articleSection":["Europa","Irland"],"inLanguage":"nb-NO"},{"@type":"WebPage","@id":"https:\/\/www.nordicjobsabroad.com\/visum-pas-irland","url":"https:\/\/www.nordicjobsabroad.com\/visum-pas-irland","name":"Visum og pass til Irland - Hvilke regler gjelder for nordmenn?","isPartOf":{"@id":"https:\/\/www.nordicjobsabroad.com\/en\/#website"},"datePublished":"2015-07-17T20:20:51+00:00","dateModified":"2024-02-29T15:03:08+00:00","description":"Nordmenn trenger ikke visum til Irland de f\u00f8rste 90 dagene av oppholdet. Les mer om pass- og visumregler for Irland p\u00e5 denne siden.","breadcrumb":{"@id":"https:\/\/www.nordicjobsabroad.com\/visum-pas-irland#breadcrumb"},"inLanguage":"nb-NO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nordicjobsabroad.com\/visum-pas-irland"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.nordicjobsabroad.com\/visum-pas-irland#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.nordicjobsabroad.com\/"},{"@type":"ListItem","position":2,"name":"Visum og pas til Irland"}]},{"@type":"WebSite","@id":"https:\/\/www.nordicjobsabroad.com\/en\/#website","url":"https:\/\/www.nordicjobsabroad.com\/en\/","name":"NordicJobsAbroad","description":"Jobb i utlandet for nordisktalende","publisher":{"@id":"https:\/\/www.nordicjobsabroad.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nordicjobsabroad.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nb-NO"},{"@type":"Organization","@id":"https:\/\/www.nordicjobsabroad.com\/en\/#organization","name":"NordicJobsAbroad","url":"https:\/\/www.nordicjobsabroad.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"nb-NO","@id":"https:\/\/www.nordicjobsabroad.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.nordicjobsabroad.com\/wp-content\/uploads\/nordicjobsabroad-logo-new.png","contentUrl":"https:\/\/www.nordicjobsabroad.com\/wp-content\/uploads\/nordicjobsabroad-logo-new.png","width":1536,"height":200,"caption":"NordicJobsAbroad"},"image":{"@id":"https:\/\/www.nordicjobsabroad.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.nordicjobsabroad.com\/en\/#\/schema\/person\/13dfb8e4bfd8eda10d75a65b2405d3a0","name":"Jesper","image":{"@type":"ImageObject","inLanguage":"nb-NO","@id":"https:\/\/secure.gravatar.com\/avatar\/5ff46f83ce962a741bd719be7cb170e6ec9041c021a913406ca1498bec6a5b7e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5ff46f83ce962a741bd719be7cb170e6ec9041c021a913406ca1498bec6a5b7e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5ff46f83ce962a741bd719be7cb170e6ec9041c021a913406ca1498bec6a5b7e?s=96&d=mm&r=g","caption":"Jesper"}}]}},"_links":{"self":[{"href":"https:\/\/www.nordicjobsabroad.com\/nb\/wp-json\/wp\/v2\/posts\/381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nordicjobsabroad.com\/nb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nordicjobsabroad.com\/nb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nordicjobsabroad.com\/nb\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nordicjobsabroad.com\/nb\/wp-json\/wp\/v2\/comments?post=381"}],"version-history":[{"count":10,"href":"https:\/\/www.nordicjobsabroad.com\/nb\/wp-json\/wp\/v2\/posts\/381\/revisions"}],"predecessor-version":[{"id":765,"href":"https:\/\/www.nordicjobsabroad.com\/nb\/wp-json\/wp\/v2\/posts\/381\/revisions\/765"}],"wp:attachment":[{"href":"https:\/\/www.nordicjobsabroad.com\/nb\/wp-json\/wp\/v2\/media?parent=381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nordicjobsabroad.com\/nb\/wp-json\/wp\/v2\/categories?post=381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nordicjobsabroad.com\/nb\/wp-json\/wp\/v2\/tags?post=381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}