{"id":129,"date":"2015-07-06T12:07:55","date_gmt":"2015-07-06T12:07:55","guid":{"rendered":"http:\/\/www.nordicjobsabroad.com\/?p=129"},"modified":"2024-02-29T15:03:38","modified_gmt":"2024-02-29T15:03:38","slug":"visum-pas-malta","status":"publish","type":"post","link":"https:\/\/www.nordicjobsabroad.com\/da\/visum-pas-malta","title":{"rendered":"Visum og pas til Malta"},"content":{"rendered":"<h2>Visum og ophold<\/h2>\n<p>Visumreglerne for danskere p\u00e5 Malta er f\u00f8lgende:<\/p>\n<ul>\n<li>I de f\u00f8rste 90 dage af dit ophold, beh\u00f8ver du intet visum,\u00a0fordi man i denne periode\u00a0har et turistvisum<\/li>\n<li>Dit pas skal v\u00e6re gyldigt under hele dit ophold<\/li>\n<li>Forl\u00e6ngede og provisoriske pas anerkendes p\u00e5 Malta<\/li>\n<\/ul>\n<p>Fordi Malta er med i Schengen-aftalen, kan alle danskere rejse frit ind i landet. Ved indrejse i landet er der ingen paskontrol, s\u00e5l\u00e6nge man indrejser fra et land i Schengen-samarbejdet.<\/p>\n<hr \/>\n<p>Hvis ikke du har et dansk pas, b\u00f8r du henvende dig p\u00e5 Maltas ambassade i Danmark:<\/p>\n<\/p>\n<p><strong>Maltas Ambassade i Danmark<\/strong><br \/>\n<strong>Lille Strandstr\u00e6de 14 B<\/strong><br \/>\n<strong>1254 K\u00f8benhavn K<\/strong><br \/>\n<strong>Telefon: +45\u00a033 15 30 90<\/strong><\/p>\n<p>\n\n\n<hr \/>\n<p>Herudover g\u00e6lder f\u00f8lgende:<\/p>\n<ul>\n<li>Alle EU-borgere kan forblive p\u00e5 Malta s\u00e5 l\u00e6nge de vil, s\u00e5fremt de kan dokumentere, at de er i stand til at fors\u00f8ge sig selv<\/li>\n<\/ul>\n<ul>\n<li>Hvis man \u00f8nsker at blive p\u00e5 Malta i mere end 90 dage, skal man ans\u00f8ge om borgerskab\u00a0&#8211; alternativt kan man forlade Malta og vende tilbage igen, hvorefter man p\u00e5ny kan opholde sig\u00a090 dage i landet (l\u00e6s evt. mere om disse muligheder\u00a0i vores artikel om at <a href=\"https:\/\/www.nordicjobsabroad.com\/da\/flytte-til-malta\" class=\"local-link\">flytte til Malta<\/a>)<\/li>\n<\/ul>\n<p>En ans\u00f8gning om forl\u00e6ngelse af opholdet p\u00e5 Malta accepteres normalt, hvis kravet om \u00f8konomisk selvforsyning (og enkelte andre krav) indfries. Hvis man som\u00a0udl\u00e6nding \u00f8nsker at blive boende p\u00e5 Malta, skal man f\u00f8lge denne procedure, hver gang opholdstilladelsen skal forl\u00e6nges.<\/p>\n<p>Hvis man har til hensigt at opholde sig\u00a0l\u00e6ngere tid p\u00e5 Malta, b\u00f8r man overveje at blive borger i landet. L\u00e6s evt. mere om at <a href=\"https:\/\/www.nordicjobsabroad.com\/da\/flytte-til-malta\" class=\"local-link\">flytte til Malta her<\/a>.<\/p>\n<hr \/>\n<p>L\u00e6s evt. ogs\u00e5 om hvordan det er <a href=\"https:\/\/www.nordicjobsabroad.com\/da\/arbejde-paa-malta\" class=\"local-link\">at arbejde p\u00e5 Malta her<\/a>\u00a0og hvordan du <a href=\"https:\/\/www.nordicjobsabroad.com\/da\/job-paa-malta\" class=\"local-link\">finder et job p\u00e5 Malta her<\/a>.<\/p>\n<hr \/>\n","protected":false},"excerpt":{"rendered":"<p>Visum og ophold Visumreglerne for danskere p\u00e5 Malta er f\u00f8lgende: I de f\u00f8rste 90 dage af dit ophold, beh\u00f8ver du intet visum,\u00a0fordi man i denne periode\u00a0har et turistvisum Dit pas skal v\u00e6re gyldigt under hele dit ophold Forl\u00e6ngede og provisoriske pas anerkendes p\u00e5 Malta Fordi Malta er med i Schengen-aftalen, kan alle danskere rejse frit &#8230; <a title=\"Visum og pas til Malta\" class=\"read-more\" href=\"https:\/\/www.nordicjobsabroad.com\/da\/visum-pas-malta\" aria-label=\"Read more about Visum og pas til Malta\">L\u00e6s mere <\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20,28],"tags":[39,68],"class_list":["post-129","post","type-post","status-publish","format-standard","hentry","category-europa","category-malta","tag-malta","tag-visum-pas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Visum og pas til Malta - L\u00e6s dette inden du rejser<\/title>\n<meta name=\"description\" content=\"Visum er ikke n\u00f8dvendigt for danskere og andre EU-borgere, der \u00f8nsker at rejse til Malta. Pas skal medbringes, men ikke vises ved gr\u00e6nsen. L\u00e6s mere her.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nordicjobsabroad.com\/da\/visum-pas-malta\/\" \/>\n<meta property=\"og:locale\" content=\"da_DK\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Visum og pas til Malta - L\u00e6s dette inden du rejser\" \/>\n<meta property=\"og:description\" content=\"Visum er ikke n\u00f8dvendigt for danskere og andre EU-borgere, der \u00f8nsker at rejse til Malta. Pas skal medbringes, men ikke vises ved gr\u00e6nsen. L\u00e6s mere her.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nordicjobsabroad.com\/da\/visum-pas-malta\/\" \/>\n<meta property=\"og:site_name\" content=\"NordicJobsAbroad\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-06T12:07:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-29T15:03:38+00:00\" \/>\n<meta name=\"author\" content=\"Jesper\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Skrevet af\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jesper\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimeret l\u00e6setid\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutter\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/visum-pas-malta#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/visum-pas-malta\"},\"author\":{\"name\":\"Jesper\",\"@id\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/en\\\/#\\\/schema\\\/person\\\/13dfb8e4bfd8eda10d75a65b2405d3a0\"},\"headline\":\"Visum og pas til Malta\",\"datePublished\":\"2015-07-06T12:07:55+00:00\",\"dateModified\":\"2024-02-29T15:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/visum-pas-malta\"},\"wordCount\":340,\"publisher\":{\"@id\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/en\\\/#organization\"},\"keywords\":[\"Malta\",\"Visum - pas\"],\"articleSection\":[\"Europa\",\"Malta\"],\"inLanguage\":\"da-DK\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/visum-pas-malta\",\"url\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/visum-pas-malta\",\"name\":\"Visum og pas til Malta - L\u00e6s dette inden du rejser\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/en\\\/#website\"},\"datePublished\":\"2015-07-06T12:07:55+00:00\",\"dateModified\":\"2024-02-29T15:03:38+00:00\",\"description\":\"Visum er ikke n\u00f8dvendigt for danskere og andre EU-borgere, der \u00f8nsker at rejse til Malta. Pas skal medbringes, men ikke vises ved gr\u00e6nsen. L\u00e6s mere her.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/visum-pas-malta#breadcrumb\"},\"inLanguage\":\"da-DK\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.nordicjobsabroad.com\\\/visum-pas-malta\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/visum-pas-malta#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Visum og pas til Malta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/en\\\/\",\"name\":\"NordicJobsAbroad\",\"description\":\"Jobs abroad for nordic speakers\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"da-DK\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/en\\\/#organization\",\"name\":\"NordicJobsAbroad\",\"url\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"da-DK\",\"@id\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/wp-content\\\/uploads\\\/nordicjobsabroad-logo-new.png\",\"contentUrl\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/wp-content\\\/uploads\\\/nordicjobsabroad-logo-new.png\",\"width\":1536,\"height\":200,\"caption\":\"NordicJobsAbroad\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.nordicjobsabroad.com\\\/en\\\/#\\\/schema\\\/person\\\/13dfb8e4bfd8eda10d75a65b2405d3a0\",\"name\":\"Jesper\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"da-DK\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ff46f83ce962a741bd719be7cb170e6ec9041c021a913406ca1498bec6a5b7e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ff46f83ce962a741bd719be7cb170e6ec9041c021a913406ca1498bec6a5b7e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ff46f83ce962a741bd719be7cb170e6ec9041c021a913406ca1498bec6a5b7e?s=96&d=mm&r=g\",\"caption\":\"Jesper\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Visum og pas til Malta - L\u00e6s dette inden du rejser","description":"Visum er ikke n\u00f8dvendigt for danskere og andre EU-borgere, der \u00f8nsker at rejse til Malta. Pas skal medbringes, men ikke vises ved gr\u00e6nsen. L\u00e6s mere her.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nordicjobsabroad.com\/da\/visum-pas-malta\/","og_locale":"da_DK","og_type":"article","og_title":"Visum og pas til Malta - L\u00e6s dette inden du rejser","og_description":"Visum er ikke n\u00f8dvendigt for danskere og andre EU-borgere, der \u00f8nsker at rejse til Malta. Pas skal medbringes, men ikke vises ved gr\u00e6nsen. L\u00e6s mere her.","og_url":"https:\/\/www.nordicjobsabroad.com\/da\/visum-pas-malta\/","og_site_name":"NordicJobsAbroad","article_published_time":"2015-07-06T12:07:55+00:00","article_modified_time":"2024-02-29T15:03:38+00:00","author":"Jesper","twitter_card":"summary_large_image","twitter_misc":{"Skrevet af":"Jesper","Estimeret l\u00e6setid":"2 minutter"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.nordicjobsabroad.com\/visum-pas-malta#article","isPartOf":{"@id":"https:\/\/www.nordicjobsabroad.com\/visum-pas-malta"},"author":{"name":"Jesper","@id":"https:\/\/www.nordicjobsabroad.com\/en\/#\/schema\/person\/13dfb8e4bfd8eda10d75a65b2405d3a0"},"headline":"Visum og pas til Malta","datePublished":"2015-07-06T12:07:55+00:00","dateModified":"2024-02-29T15:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.nordicjobsabroad.com\/visum-pas-malta"},"wordCount":340,"publisher":{"@id":"https:\/\/www.nordicjobsabroad.com\/en\/#organization"},"keywords":["Malta","Visum - pas"],"articleSection":["Europa","Malta"],"inLanguage":"da-DK"},{"@type":"WebPage","@id":"https:\/\/www.nordicjobsabroad.com\/visum-pas-malta","url":"https:\/\/www.nordicjobsabroad.com\/visum-pas-malta","name":"Visum og pas til Malta - L\u00e6s dette inden du rejser","isPartOf":{"@id":"https:\/\/www.nordicjobsabroad.com\/en\/#website"},"datePublished":"2015-07-06T12:07:55+00:00","dateModified":"2024-02-29T15:03:38+00:00","description":"Visum er ikke n\u00f8dvendigt for danskere og andre EU-borgere, der \u00f8nsker at rejse til Malta. Pas skal medbringes, men ikke vises ved gr\u00e6nsen. L\u00e6s mere her.","breadcrumb":{"@id":"https:\/\/www.nordicjobsabroad.com\/visum-pas-malta#breadcrumb"},"inLanguage":"da-DK","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nordicjobsabroad.com\/visum-pas-malta"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.nordicjobsabroad.com\/visum-pas-malta#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.nordicjobsabroad.com\/"},{"@type":"ListItem","position":2,"name":"Visum og pas til Malta"}]},{"@type":"WebSite","@id":"https:\/\/www.nordicjobsabroad.com\/en\/#website","url":"https:\/\/www.nordicjobsabroad.com\/en\/","name":"NordicJobsAbroad","description":"Jobs abroad for nordic speakers","publisher":{"@id":"https:\/\/www.nordicjobsabroad.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nordicjobsabroad.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"da-DK"},{"@type":"Organization","@id":"https:\/\/www.nordicjobsabroad.com\/en\/#organization","name":"NordicJobsAbroad","url":"https:\/\/www.nordicjobsabroad.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"da-DK","@id":"https:\/\/www.nordicjobsabroad.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.nordicjobsabroad.com\/wp-content\/uploads\/nordicjobsabroad-logo-new.png","contentUrl":"https:\/\/www.nordicjobsabroad.com\/wp-content\/uploads\/nordicjobsabroad-logo-new.png","width":1536,"height":200,"caption":"NordicJobsAbroad"},"image":{"@id":"https:\/\/www.nordicjobsabroad.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.nordicjobsabroad.com\/en\/#\/schema\/person\/13dfb8e4bfd8eda10d75a65b2405d3a0","name":"Jesper","image":{"@type":"ImageObject","inLanguage":"da-DK","@id":"https:\/\/secure.gravatar.com\/avatar\/5ff46f83ce962a741bd719be7cb170e6ec9041c021a913406ca1498bec6a5b7e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5ff46f83ce962a741bd719be7cb170e6ec9041c021a913406ca1498bec6a5b7e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5ff46f83ce962a741bd719be7cb170e6ec9041c021a913406ca1498bec6a5b7e?s=96&d=mm&r=g","caption":"Jesper"}}]}},"_links":{"self":[{"href":"https:\/\/www.nordicjobsabroad.com\/da\/wp-json\/wp\/v2\/posts\/129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nordicjobsabroad.com\/da\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nordicjobsabroad.com\/da\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nordicjobsabroad.com\/da\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nordicjobsabroad.com\/da\/wp-json\/wp\/v2\/comments?post=129"}],"version-history":[{"count":37,"href":"https:\/\/www.nordicjobsabroad.com\/da\/wp-json\/wp\/v2\/posts\/129\/revisions"}],"predecessor-version":[{"id":785,"href":"https:\/\/www.nordicjobsabroad.com\/da\/wp-json\/wp\/v2\/posts\/129\/revisions\/785"}],"wp:attachment":[{"href":"https:\/\/www.nordicjobsabroad.com\/da\/wp-json\/wp\/v2\/media?parent=129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nordicjobsabroad.com\/da\/wp-json\/wp\/v2\/categories?post=129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nordicjobsabroad.com\/da\/wp-json\/wp\/v2\/tags?post=129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}